{"id":1015,"date":"2025-06-04T00:32:24","date_gmt":"2025-06-04T00:32:24","guid":{"rendered":"https:\/\/habitacionpropia.mx\/?p=1015"},"modified":"2025-06-04T00:32:26","modified_gmt":"2025-06-04T00:32:26","slug":"entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias","status":"publish","type":"post","link":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/","title":{"rendered":"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En una ciudad donde moverse a pie o en bicicleta puede ser un riesgo, especialmente para mujeres, infancias y personas LGBTTTIQA+, <strong>el proyecto <em>Entornos Amables<\/em> se prepara para volver al sur de M\u00e9rida.<\/strong> Este 2025, inicia su tercera edici\u00f3n con una meta clara: visibilizar la vivencia de mujeres que cuidan a otras personas, tanto infancias como a personas con discapacidad o de la tercera edad.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u201cSe fortalecer\u00e1n los cuidados personales como base para el cuidado colectivo;<\/strong> las herramientas para apropiarse del espacio p\u00fablico depender\u00e1n de los intereses de las personas que sean parte de este proyecto\u201d, <\/p>\n<cite>mencion\u00f3 Paola Becerra, coordinadora del eje de mujeres y territorios en la Red de Acciones Feministas (RAF).<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, sumar\u00e1 un nuevo componente: <strong>los cuidados<\/strong>, incorporando la experiencia de mujeres que cuidan a infancias, personas con discapacidad o de la tercera edad, para fortalecer los cuidados personales y el cuidado colectivo como parte de la apropiaci\u00f3n del espacio p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ediciones anteriores del proyecto <em>Entornos Amables<\/em>, la RAF ha trabajado de la mano con Estrategia Misi\u00f3n Cero, enfoc\u00e1ndose en zonas donde coinciden hechos de tr\u00e1nsito, desplazamientos no motorizados y usos habitacionales del suelo.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1017\" data-id=\"1017\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-1024x1024.png\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-1024x1024.png 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-300x300.png 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-150x150.png 150w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-768x768.png 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-435x435.png 435w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-60x60.png 60w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024-600x600.png 600w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_024.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1018\" data-id=\"1018\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/UABIC-Previoalmural-14-de-16-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1020\" data-id=\"1020\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-27-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los momentos m\u00e1s significativos del proyecto fue la segunda sesi\u00f3n titulada <em>Retoma la Calle<\/em>, realizada el pasado 30 de agosto. En esta actividad, 26 participantes \u2014organizadas en dos grupos\u2014 recorrieron rutas cercanas a su instituci\u00f3n educativa con el objetivo de<strong> identificar zonas seguras e inseguras. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lo hicieron desde una perspectiva cr\u00edtica y emp\u00e1tica: <\/strong>algunas asumieron roles como fot\u00f3grafas, relatoras o responsables de seguridad; otras, realizaron el recorrido simulando condiciones distintas a las propias \u2014discapacidad motriz, ser persona mayor, afrodescendiente, trans o de pueblos originarios\u2014 para incorporar un enfoque interseccional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el recorrido se identificaron m\u00faltiples factores de riesgo: calles mal iluminadas, aceras en mal estado, acumulaci\u00f3n de basura, terrenos bald\u00edos y domicilios donde se han registrado acosos verbales reiterados hacia estudiantes.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u201cLas j\u00f3venes expresaron sentir vulnerabilidad al transitar por zonas cercanas a expendios de alcohol\u201d, se document\u00f3.&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, tambi\u00e9n afirmaron que realizar el recorrido en grupo les brind\u00f3 seguridad y fortaleci\u00f3 su sentido de comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ejercicio no s\u00f3lo permiti\u00f3 visibilizar las condiciones del entorno urbano, sino que <strong>motiv\u00f3 a las participantes a proponer soluciones concretas para mejorar la seguridad en su comunidad.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las dos ediciones anteriores de <em>Entornos Amables<\/em> tambi\u00e9n se realizaron en la zona sur de M\u00e9rida, en la Escuela Primaria Raquel Dzib Cicero (2023) y la Preparatoria 3 (UABIC) de la Universidad Aut\u00f3noma de Yucat\u00e1n (2024). <strong>En estos espacios se conjugaron herramientas de urbanismo t\u00e1ctico, educaci\u00f3n en movilidad segura, an\u00e1lisis territorial y expresi\u00f3n art\u00edstica<\/strong> para promover el derecho a la ciudad con perspectiva feminista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En la primaria, se pintaron pasos peatonales y se imparti\u00f3 una biciescuela para infancias.<\/strong> Las cuidadoras \u2014madres, abuelas y otras mujeres del entorno\u2014 se sumaron de forma espont\u00e1nea y terminaron organiz\u00e1ndose como gestoras del espacio; fue as\u00ed como surgi\u00f3 sumar el enfoque hacia las cuidadoras en la edici\u00f3n venidera.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1019\" data-id=\"1019\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-1024x683.jpeg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-1024x683.jpeg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-300x200.jpeg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-768x512.jpeg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-1536x1024.jpeg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-2048x1365.jpeg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-450x300.jpeg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-90x60.jpeg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-1320x880.jpeg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/1-600x400.jpeg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1021\" data-id=\"1021\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-25-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1022\" data-id=\"1022\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/Ninez_al_pedal-14-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En la preparatoria, adem\u00e1s del mapeo <em>Retoma la Calle<\/em>, se desarrollaron <strong>talleres sobre seguridad ciclista y un mural colectivo<\/strong> que visibiliz\u00f3 las experiencias de acoso y violencia vividas en el espacio p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tercera sesi\u00f3n del proyecto, titulada <em>Mujeres al Pedal<\/em>, profundiz\u00f3 en el conocimiento sobre la bicicleta como medio de movilidad cotidiana. <strong>Las participantes aprendieron sobre anatom\u00eda de la bicicleta, mec\u00e1nica b\u00e1sica y normas de tr\u00e1nsito, fortaleciendo su autonom\u00eda<\/strong> y capacidad de respuesta ante los riesgos del entorno urbano.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1023\" data-id=\"1023\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7674-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1024\" data-id=\"1024\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7679-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1026\" data-id=\"1026\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7685-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1028\" data-id=\"1028\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-1024x683.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-1024x683.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-300x200.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-768x512.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-1536x1024.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-2048x1365.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-450x300.jpg 450w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-90x60.jpg 90w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-1320x880.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/IMG_7694-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Datos que exigen respuestas<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el \u00faltimo conteo ciclista realizado por el proyecto se identificaron 1,734 personas en tr\u00e1nsito, de las cuales solo el 11.6% eran mujeres. Aunque esto representa un aumento respecto al 5% registrado en 2014, la diferencia sigue siendo abismal. Adem\u00e1s, <strong>en encuestas aplicadas durante la actividad, las mujeres manifestaron miedo al moverse por la ciudad<\/strong> \u2014miedo al acoso, al hostigamiento, a la inseguridad vial\u2014 mientras que el 100% de los hombres encuestados dijo sentirse seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No se trata solo de violencia vial, sino de violencia de g\u00e9nero.<\/strong> Las mujeres y disidencias son agredidas por c\u00f3mo se perciben en el espacio.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cLas mujeres s\u00ed nombraban el miedo al transitar, entonces es violencia vial, pero tambi\u00e9n violencia de g\u00e9nero. En la encuesta no hubo un solo hombre que dijera que se sent\u00eda inseguro\u201d, <\/p>\n<cite>Paola Becerra, representante de RAF.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los resultados del conteo a\u00fan no han sido retomados por autoridades gubernamentales, han servido como punto de partida para el di\u00e1logo comunitario en las escuelas y colonias involucradas.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1025\" data-id=\"1025\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-1024x1024.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-1024x1024.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-300x300.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-150x150.jpg 150w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-768x768.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-1536x1536.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-2048x2048.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-435x435.jpg 435w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-60x60.jpg 60w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-1320x1320.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01342-600x600.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1027\" data-id=\"1027\" src=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-1024x1024.jpg\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-1024x1024.jpg 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-300x300.jpg 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-150x150.jpg 150w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-768x768.jpg 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-1536x1536.jpg 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-2048x2048.jpg 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-435x435.jpg 435w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-60x60.jpg 60w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-1320x1320.jpg 1320w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/DSC01481-600x600.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La edici\u00f3n 2025 de <em>Entornos Amables<\/em> continuar\u00e1 con las acciones de mapeo, talleres y urbanismo t\u00e1ctico. Esta vez, el proyecto incorporar\u00e1 el componente de cuidados para trabajar directamente con mujeres cuidadoras, fortalecer sus herramientas y construir colectivamente espacios m\u00e1s seguros y habitables.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Un entorno amable no es solo un cruce pintado o una ciclov\u00eda. Es un lugar donde las personas se sienten vistas, escuchadas y capaces de moverse sin miedo.<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"http:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-1024x512.png\" alt=\"\" class=\"wp-image-515\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-1024x512.png 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-300x150.png 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-768x384.png 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-1536x768.png 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-2048x1024.png 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-120x60.png 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Entornos Amables es un proyecto de RAF, que visibiliza la movilidad en bicicleta, al mismo tiempo que reconoce las vivencias que enfrentan las mujeres al desplazarse sobre dos ruedas<\/p>\n","protected":false},"author":4,"featured_media":1016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[69],"tags":[328,325,326,324,327,330,20,323,44,76,86],"class_list":["post-1015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gato-negro","tag-autocuidado","tag-ciclismo","tag-ciclismo-urbano","tag-ciclistas","tag-cuidados-colectivos","tag-entornos-amables","tag-lucha","tag-movilidad","tag-mujeres","tag-violencia-de-genero","tag-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias - Habitaci\u00f3n Propia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias - Habitaci\u00f3n Propia\" \/>\n<meta property=\"og:description\" content=\"Entornos Amables es un proyecto de RAF, que visibiliza la movilidad en bicicleta, al mismo tiempo que reconoce las vivencias que enfrentan las mujeres al desplazarse sobre dos ruedas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\" \/>\n<meta property=\"og:site_name\" content=\"Habitaci\u00f3n Propia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/habitacionpropia.mx\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-04T00:32:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T00:32:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6\"},\"headline\":\"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias\",\"datePublished\":\"2025-06-04T00:32:24+00:00\",\"dateModified\":\"2025-06-04T00:32:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\"},\"wordCount\":872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#organization\"},\"image\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png\",\"keywords\":[\"autocuidado\",\"ciclismo\",\"ciclismo urbano\",\"ciclistas\",\"cuidados colectivos\",\"Entornos Amables\",\"Lucha\",\"movilidad\",\"mujeres\",\"violencia de g\u00e9nero\",\"Yucat\u00e1n\"],\"articleSection\":[\"Gata Negra\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\",\"url\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\",\"name\":\"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias - Habitaci\u00f3n Propia\",\"isPartOf\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png\",\"datePublished\":\"2025-06-04T00:32:24+00:00\",\"dateModified\":\"2025-06-04T00:32:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage\",\"url\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png\",\"contentUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/habitacionpropia.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/habitacionpropia.mx\/#website\",\"url\":\"https:\/\/habitacionpropia.mx\/\",\"name\":\"Habitaci\u00f3n Propia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/habitacionpropia.mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/habitacionpropia.mx\/#organization\",\"name\":\"Habitaci\u00f3n Propia\",\"url\":\"https:\/\/habitacionpropia.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png\",\"contentUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png\",\"width\":846,\"height\":191,\"caption\":\"Habitaci\u00f3n Propia\"},\"image\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/habitacionpropia.mx\",\"https:\/\/www.instagram.com\/habitacionpropia.mx\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\/\/habitacionpropia.mx\/index.php\/author\/redaccion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias - Habitaci\u00f3n Propia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/","og_locale":"es_MX","og_type":"article","og_title":"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias - Habitaci\u00f3n Propia","og_description":"Entornos Amables es un proyecto de RAF, que visibiliza la movilidad en bicicleta, al mismo tiempo que reconoce las vivencias que enfrentan las mujeres al desplazarse sobre dos ruedas","og_url":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/","og_site_name":"Habitaci\u00f3n Propia","article_publisher":"https:\/\/www.facebook.com\/habitacionpropia.mx","article_published_time":"2025-06-04T00:32:24+00:00","article_modified_time":"2025-06-04T00:32:26+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0-1024x1024.png","type":"image\/png"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#article","isPartOf":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6"},"headline":"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias","datePublished":"2025-06-04T00:32:24+00:00","dateModified":"2025-06-04T00:32:26+00:00","mainEntityOfPage":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/"},"wordCount":872,"commentCount":0,"publisher":{"@id":"https:\/\/habitacionpropia.mx\/#organization"},"image":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage"},"thumbnailUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png","keywords":["autocuidado","ciclismo","ciclismo urbano","ciclistas","cuidados colectivos","Entornos Amables","Lucha","movilidad","mujeres","violencia de g\u00e9nero","Yucat\u00e1n"],"articleSection":["Gata Negra"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/","url":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/","name":"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias - Habitaci\u00f3n Propia","isPartOf":{"@id":"https:\/\/habitacionpropia.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage"},"image":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage"},"thumbnailUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png","datePublished":"2025-06-04T00:32:24+00:00","dateModified":"2025-06-04T00:32:26+00:00","breadcrumb":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#primaryimage","url":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png","contentUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/06\/04\/entornos-amables-regresa-al-sur-de-merida-por-la-seguridad-vial-con-enfoque-de-genero-e-infancias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/habitacionpropia.mx\/"},{"@type":"ListItem","position":2,"name":"Entornos Amables regresa al sur de M\u00e9rida, por la seguridad vial con enfoque de g\u00e9nero e infancias"}]},{"@type":"WebSite","@id":"https:\/\/habitacionpropia.mx\/#website","url":"https:\/\/habitacionpropia.mx\/","name":"Habitaci\u00f3n Propia","description":"","publisher":{"@id":"https:\/\/habitacionpropia.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/habitacionpropia.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/habitacionpropia.mx\/#organization","name":"Habitaci\u00f3n Propia","url":"https:\/\/habitacionpropia.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/","url":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png","contentUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png","width":846,"height":191,"caption":"Habitaci\u00f3n Propia"},"image":{"@id":"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/habitacionpropia.mx","https:\/\/www.instagram.com\/habitacionpropia.mx\/"]},{"@type":"Person","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/habitacionpropia.mx\/index.php\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/06\/ENTORNOSAMABLES_0.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts\/1015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1015"}],"version-history":[{"count":1,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts\/1015\/revisions"}],"predecessor-version":[{"id":1029,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts\/1015\/revisions\/1029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/media\/1016"}],"wp:attachment":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}