{"id":1594,"date":"2025-11-13T00:13:21","date_gmt":"2025-11-13T00:13:21","guid":{"rendered":"https:\/\/habitacionpropia.mx\/?p=1594"},"modified":"2025-11-13T00:13:24","modified_gmt":"2025-11-13T00:13:24","slug":"once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten","status":"publish","type":"post","link":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/","title":{"rendered":"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El festival yucateco de cine contempor\u00e1neo que llega a su onceava edici\u00f3n con la presentaci\u00f3n de casi <strong>20 largometrajes<\/strong>, ocho personas invitadas* y\u00a0<strong>siete programas de cortos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Emmanuel Tatto P\u00e9rez, director y programador de Libre Cinema Festival expres\u00f3 que con estos a\u00f1os de trayectoria, el festival ha mejorado su log\u00edstica, difusi\u00f3n y la conceptualizaci\u00f3n del proyecto, alcanzando una programaci\u00f3n con una curadur\u00eda profesional en el material audiovisual que proyectan.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>\u201cNo hay otra plataforma como esta en la Pen\u00ednsula de Yucat\u00e1n, es decir, un festival que se dedique exclusivamente a difundir el cine regional y mexicano\u201d, se\u00f1al\u00f3.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esto permite&nbsp;<strong>conectar y acercar el cine a la regi\u00f3n<\/strong>&nbsp;y&nbsp;<strong>visibilizar que aqu\u00ed tambi\u00e9n se desarrolla el s\u00e9ptimo arte,&nbsp;<\/strong>porque el festival es un encuentro para ver cine y un medio para exhibir y producir el trabajo local, abriendo oportunidades para el talento que nace desde el sur; as\u00ed lo dio a conocer Tatto P\u00e9rez.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEl programa consiste en propuestas que van desde las&nbsp;<strong>pel\u00edculas ganadoras en los principales festivales de M\u00e9xico<\/strong>, hasta propuestas vanguardistas y de diversas tem\u00e1ticas art\u00edsticas y sociales (feminismo, LGBT+, entre otros)\u201d, agreg\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Patricia Mart\u00edn, secretaria de la Cultura y las Artes (Sedeculta), resalt\u00f3 que el slogan \u201cLibre\u201d que acompa\u00f1a a esta edici\u00f3n&nbsp;<strong>es muy importante porque refleja lo que han construido desde el festival y, al mismo tiempo, con el p\u00e1jaro Toh como imagen, transmiten la cultura local.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEl cine, como la cultura en su conjunto, es eso: un acto de encuentro\u201d, expres\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Emmanuel Tatto, destac\u00f3 que en el uso del p\u00e1jaro Toh reconocen la identidad local.&nbsp;<strong>Para Libre Cinema Festival, es un ave peninsular libre, como el cine que se gesta en la regi\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subray\u00f3 tambi\u00e9n que reconociendo la importancia de descentralizar la cultura, las convocatorias que realizaron \u2013explicadas m\u00e1s adelante\u2013 estuvieron enfocadas para la capital yucateca y para el sur-sureste, incluyendo a Tabasco, Chiapas, Quintana Roo, entre otros estados.&nbsp;<strong>Con el mismo objetivo, tambi\u00e9n esperan expandir proyecciones al interior del estado.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martha Uc, cineasta, presenta el cortometraje de 16 minutos, \u201cCremita de coco\u201d, realizado en la comunidad de&nbsp;<strong>Sudzal, con Cendi como protagonista, una madre que vendiendo cremitas de coco retrata la resiliencia, su amor maternal y sue\u00f1os.<\/strong>&nbsp;En este evento se vender\u00e1n sus cremitas de&nbsp;de coco a 25 pesos, durante la funci\u00f3n.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEs muy importante aportar esta mirada sobre Yucat\u00e1n, creo que no&nbsp;solo hay que descentralizar de la Ciudad de M\u00e9xico, sino tambi\u00e9n de&nbsp;M\u00e9rida\u201d, expres\u00f3 la cineasta.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Para ella, irse a las comunidades, es recordar a su madre que naci\u00f3 en Hocab\u00e1, y precisamente este corto est\u00e1 dedicado a ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Puedes adquirir tus boletos a trav\u00e9s de las redes sociales de Libre Cinema Festival<\/strong>&nbsp;\u2013<a href=\"https:\/\/www.instagram.com\/librecinemafestival\/\"><strong>Instagram<\/strong><\/a>&nbsp;y&nbsp;<a href=\"https:\/\/www.facebook.com\/LibreCinemaFestival\"><strong>Facebook<\/strong><\/a>\u2013<strong>&nbsp;o directamente en la taquilla;<\/strong>&nbsp;el boleto sencillo por funci\u00f3n tiene un costo de 40 pesos, el boleto por d\u00eda, 60 pesos y este incluye todas las funciones disponibles, mientras que el acceso a todo el festival tiene una cuota de 299 pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/librecinemafestival.com\/wp-content\/uploads\/2025\/11\/PROGRAMA-LIBRECINEMA2025-2.pdf\"><strong>Aqu\u00ed<\/strong><\/a><strong>&nbsp;puedes consultar la cartelera del festival&nbsp;<\/strong>que tendr\u00e1 como sede la Cineteca del Teatro Armando Manzanero. La inauguraci\u00f3n ser\u00e1 el s\u00e1bado 15 de noviembre a las 19:30 horas con la funci\u00f3n \u201cA\u00fan es de noche en Caracas\u201d, de las realizadoras Mariana Rond\u00f3n y Marit\u00e9 Ug\u00e1s. Con la presencia de la productora asociada y realizadora Camila Balzaretti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El domingo 16 de noviembre, la pel\u00edcula \u201cSay Goodbye\u201d ser\u00e1 proyectada a las 17:30 horas y contar\u00e1 con la presencia de la directora Paloma L\u00f3pez. A las 19:45, tambi\u00e9n con la compa\u00f1\u00eda de su director \u2013Yovegami Ascona\u2013, ser\u00e1 proyectada \u201cBoca Vieja\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quienes tienen inter\u00e9s en conocer a quienes est\u00e1n detr\u00e1s de las pel\u00edculas, el lunes 17 de noviembre a las 19:30 tienen una cita con \u201cLlamarse Olimpia\u201d y su directora, Indira Cato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mi\u00e9rcoles, el director Rafael Ru\u00edz Espejo, de la pel\u00edcula \u201cEl fin de las primeras veces\u201d estar\u00e1 presente en la proyecci\u00f3n de las 20:00 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viernes, tambi\u00e9n a las 20:00 horas, en la proyecci\u00f3n \u201cUn techo sin cielo\u201d, las personas conocer\u00e1n al director Diego Hern\u00e1ndez. Su presencia es muy importante, por ser uno de los directores j\u00f3venes destacados en el panorama del cine mexicano con una propuesta imperdible.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y para finalizar el festival, el s\u00e1bado 22 de noviembre a las 19:20 horas se llevar\u00e1 a cabo la ceremonia de clausura, con la proyecci\u00f3n de \u201cLa eterna adolescente\u201d en presencia del director de la pel\u00edcula, Eduardo Esquivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Libre Cinema Festival agradece a la Secretar\u00eda de la Cultura y las Artes (Sedeculta) por el apoyo para hacer posible esta edici\u00f3n. As\u00ed como al Instituto Mexicano de Cinematograf\u00eda (Imcine), a trav\u00e9s del Programa de Fomento al Cine Mexicano (Focine) por su apoyo para realizar este proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Impulso al talento cinematogr\u00e1fico&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Libre Cinema Festival, es m\u00e1s que un evento de proyecci\u00f3n,&nbsp;<\/strong>actualmente, es tambi\u00e9n un medio para impulsar el talento local a trav\u00e9s de convocatorias para desarrollar cortos y otros productos audiovisuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o en particular, abrieron dos convocatorias:<br>1.&nbsp;<a href=\"https:\/\/librecinemafestival.com\/wp-content\/uploads\/2025\/09\/CONVOCATORIA-CORTOMETRAJE-2025.pdf\"><strong>Cortometraje<\/strong><br><\/a>2.&nbsp;<a href=\"https:\/\/librecinemafestival.com\/wp-content\/uploads\/2025\/09\/CONVOCATORIA-PRODUCCION-2025.pdf\"><strong>Apoyo a la Producci\u00f3n<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jurado para la selecci\u00f3n de los proyectos fue seleccionado tambi\u00e9n a trav\u00e9s de una convocatoria. La convocatoria&nbsp;<a href=\"https:\/\/librecinemafestival.com\/wp-content\/uploads\/2025\/09\/JURADO-JOVEN.pdf\"><strong>Jurado Joven<\/strong><\/a>&nbsp;acept\u00f3 a personas de la Pen\u00ednsula de Yucat\u00e1n, con edad entre 18 y 27 a\u00f1os.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En particular, sobre&nbsp;<strong>la convocatoria para la realizaci\u00f3n de cortometrajes,&nbsp;<\/strong>el director del festival inform\u00f3 que&nbsp;<strong>tuvo un enorme alcance,<\/strong>&nbsp;incluso internacional. De dicha convocatoria<strong>&nbsp;recibieron casi 300 propuestas,&nbsp;<\/strong>entre las cuales el jurado joven seleccionar\u00e1 una para ser la acreedora del premio de 15 mil pesos. El premio de la convocatoria de producci\u00f3n ser\u00e1 de 35 mil pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 el s\u00e1bado 22 de noviembre a las 19:00 horas cuando den a conocer a las personas ganadoras de las convocatorias, como parte del festival.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo organizador agradece a la Sedeculta y a la Universidad de las Artes de Yucat\u00e1n (UNAY) por el apoyo para hacer posible esta edici\u00f3n, un proyecto que tambi\u00e9n cuenta con el apoyo del Instituto Mexicano de Cinematograf\u00eda a trav\u00e9s del programa Fomento al Cine Mexicano (FOCINE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma a los patrocinadores que creen en este proyecto, Payasita Inc, Vive Fundaci\u00f3n, Instituto Granados, Aar\u00f3n Gonz\u00e1lez Composer, as\u00ed como a las alianzas que hemos generado con Pan Montejo, La Lupita, Tinoc.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"http:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-1024x512.png\" alt=\"\" class=\"wp-image-515\" srcset=\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-1024x512.png 1024w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-300x150.png 300w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-768x384.png 768w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-1536x768.png 1536w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-2048x1024.png 2048w, https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/11\/Publicidad3-120x60.png 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Libre Cinema Festival es m\u00e1s que un encuentro para ver cine, es un medio para visibilizar el trabajo que se gesta en la regi\u00f3n<\/p>\n","protected":false},"author":4,"featured_media":1595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[69],"tags":[484,485,487,121,488,13,90,490,489,86],"class_list":["post-1594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gato-negro","tag-cine","tag-cine-independiente","tag-cortos","tag-festival","tag-libre-cinema-festival","tag-merida","tag-mexico","tag-peliculas","tag-peninsula-de-yucatan","tag-yucatan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten - Habitaci\u00f3n Propia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten - Habitaci\u00f3n Propia\" \/>\n<meta property=\"og:description\" content=\"Libre Cinema Festival es m\u00e1s que un encuentro para ver cine, es un medio para visibilizar el trabajo que se gesta en la regi\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\" \/>\n<meta property=\"og:site_name\" content=\"Habitaci\u00f3n Propia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/habitacionpropia.mx\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T00:13:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T00:13:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6\"},\"headline\":\"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten\",\"datePublished\":\"2025-11-13T00:13:21+00:00\",\"dateModified\":\"2025-11-13T00:13:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\"},\"wordCount\":1138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#organization\"},\"image\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg\",\"keywords\":[\"cine\",\"cine independiente\",\"cortos\",\"Festival\",\"Libre Cinema Festival\",\"M\u00e9rida\",\"M\u00e9xico\",\"pel\u00edculas\",\"Pen\u00ednsula de Yucat\u00e1n\",\"Yucat\u00e1n\"],\"articleSection\":[\"Gata Negra\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\",\"url\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\",\"name\":\"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten - Habitaci\u00f3n Propia\",\"isPartOf\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg\",\"datePublished\":\"2025-11-13T00:13:21+00:00\",\"dateModified\":\"2025-11-13T00:13:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage\",\"url\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg\",\"contentUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/habitacionpropia.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/habitacionpropia.mx\/#website\",\"url\":\"https:\/\/habitacionpropia.mx\/\",\"name\":\"Habitaci\u00f3n Propia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/habitacionpropia.mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/habitacionpropia.mx\/#organization\",\"name\":\"Habitaci\u00f3n Propia\",\"url\":\"https:\/\/habitacionpropia.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png\",\"contentUrl\":\"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png\",\"width\":846,\"height\":191,\"caption\":\"Habitaci\u00f3n Propia\"},\"image\":{\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/habitacionpropia.mx\",\"https:\/\/www.instagram.com\/habitacionpropia.mx\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/habitacionpropia.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\/\/habitacionpropia.mx\/index.php\/author\/redaccion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten - Habitaci\u00f3n Propia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/","og_locale":"es_MX","og_type":"article","og_title":"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten - Habitaci\u00f3n Propia","og_description":"Libre Cinema Festival es m\u00e1s que un encuentro para ver cine, es un medio para visibilizar el trabajo que se gesta en la regi\u00f3n","og_url":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/","og_site_name":"Habitaci\u00f3n Propia","article_publisher":"https:\/\/www.facebook.com\/habitacionpropia.mx","article_published_time":"2025-11-13T00:13:21+00:00","article_modified_time":"2025-11-13T00:13:24+00:00","og_image":[{"width":2560,"height":1920,"url":"http:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#article","isPartOf":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6"},"headline":"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten","datePublished":"2025-11-13T00:13:21+00:00","dateModified":"2025-11-13T00:13:24+00:00","mainEntityOfPage":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/"},"wordCount":1138,"commentCount":0,"publisher":{"@id":"https:\/\/habitacionpropia.mx\/#organization"},"image":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage"},"thumbnailUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg","keywords":["cine","cine independiente","cortos","Festival","Libre Cinema Festival","M\u00e9rida","M\u00e9xico","pel\u00edculas","Pen\u00ednsula de Yucat\u00e1n","Yucat\u00e1n"],"articleSection":["Gata Negra"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/","url":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/","name":"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten - Habitaci\u00f3n Propia","isPartOf":{"@id":"https:\/\/habitacionpropia.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage"},"image":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage"},"thumbnailUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg","datePublished":"2025-11-13T00:13:21+00:00","dateModified":"2025-11-13T00:13:24+00:00","breadcrumb":{"@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#primaryimage","url":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg","contentUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/habitacionpropia.mx\/index.php\/2025\/11\/13\/once-anos-de-cine-independiente-en-merida-historias-que-emocionan-y-resisten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/habitacionpropia.mx\/"},{"@type":"ListItem","position":2,"name":"Once a\u00f1os de cine independiente en M\u00e9rida: historias que emocionan y resisten"}]},{"@type":"WebSite","@id":"https:\/\/habitacionpropia.mx\/#website","url":"https:\/\/habitacionpropia.mx\/","name":"Habitaci\u00f3n Propia","description":"","publisher":{"@id":"https:\/\/habitacionpropia.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/habitacionpropia.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/habitacionpropia.mx\/#organization","name":"Habitaci\u00f3n Propia","url":"https:\/\/habitacionpropia.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/","url":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png","contentUrl":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2024\/01\/cropped-Logo-Final-1.png","width":846,"height":191,"caption":"Habitaci\u00f3n Propia"},"image":{"@id":"https:\/\/habitacionpropia.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/habitacionpropia.mx","https:\/\/www.instagram.com\/habitacionpropia.mx\/"]},{"@type":"Person","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/person\/a5d7d1860aaa98c0ffafe5e7c4a203d6","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/habitacionpropia.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbd2d6dd1b1688ce810f4e8a7fb119404f27b95517081c9e3e05be9c8e82c0e2?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/habitacionpropia.mx\/index.php\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/habitacionpropia.mx\/wp-content\/uploads\/2025\/11\/IMG_20251110_154509-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts\/1594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1594"}],"version-history":[{"count":1,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts\/1594\/revisions"}],"predecessor-version":[{"id":1596,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/posts\/1594\/revisions\/1596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/media\/1595"}],"wp:attachment":[{"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/habitacionpropia.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}